{"id":18927,"date":"2024-12-02T07:00:13","date_gmt":"2024-12-02T12:00:13","guid":{"rendered":"https:\/\/worldpressfreedomcanada.ca\/?p=18927"},"modified":"2025-01-23T00:35:10","modified_gmt":"2025-01-23T00:35:10","slug":"ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse","status":"publish","type":"post","link":"https:\/\/worldpressfreedomcanada.ca\/fr\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\/","title":{"rendered":"Ouverture des nominations pour les prix 2025 de la libert\u00e9 de la presse"},"content":{"rendered":"<h2>Les Prix mondiaux de la libert\u00e9 de la presse Canada r\u00e9compensent ceux qui affrontent le secret, d\u00e9fient l&rsquo;intimidation et surmontent des obstacles dangereux dans leur qu\u00eate de la v\u00e9rit\u00e9.<\/h2>\n<p><b>OTTAWA, 2 D\u00c9CEMBRE 2024 <\/b>\u2013 Libert\u00e9 de la presse Canada a le plaisir d&rsquo;annoncer que les candidatures pour les Prix de la libert\u00e9 de la presse 2025 et le Prix d&rsquo;excellence en carri\u00e8re en l&rsquo;honneur de Spencer Moore sont maintenant ouvertes.<\/p>\n<p>Les prix annuels de la libert\u00e9 de la presse r\u00e9compensent les candidats dont le journalisme d&rsquo;int\u00e9r\u00eat public a surmont\u00e9 des d\u00e9fis tels que le secret, les man\u0153uvres juridiques, l&rsquo;intimidation politique ou d&rsquo;autres tactiques visant \u00e0 \u00e9touffer leur travail ou \u00e0 mettre leur carri\u00e8re ou leur s\u00e9curit\u00e9 en p\u00e9ril.<\/p>\n<p>Cette ann\u00e9e, Libert\u00e9 de la presse Canada d\u00e9cernera deux prix de la libert\u00e9 de la presse, l&rsquo;un pour les grandes publications et l&rsquo;autre pour la libert\u00e9 de la presse, le journalisme local, \u00e0 un journaliste travaillant pour un organe de presse de petite taille.<\/p>\n<p>Le prix de la r\u00e9ussite professionnelle r\u00e9compense une personne qui, tout au long de sa carri\u00e8re, a fait preuve d&rsquo;une poursuite infatigable de la libert\u00e9 de la presse et de la transparence.<\/p>\n<p>Libert\u00e9 de la presse Canada remettra \u00e9galement son deuxi\u00e8me prix annuel de la r\u00e9ussite \u00e9tudiante, qui r\u00e9compense un \u00e9tudiant journaliste exceptionnel ayant fait preuve d&rsquo;un engagement en faveur de la libert\u00e9 de la presse.<\/p>\n<p>Les nominations pour le prix \u00e9tudiant sont ouvertes aux \u00e9tudiants inscrits dans un \u00e9tablissement postsecondaire canadien en 2024, dont le travail a montr\u00e9 la d\u00e9termination \u00e0 publier un article malgr\u00e9 les d\u00e9fis ou les obstacles \u00e0 la libert\u00e9 de rendre compte des questions qui importent \u00e0 leur communaut\u00e9 scolaire.<\/p>\n<p>Pour tous les prix, les travaux d\u00e9montrant cet engagement en faveur de la libert\u00e9 de la presse doivent avoir \u00e9t\u00e9 publi\u00e9s ou diffus\u00e9s en 2024.<\/p>\n<p>Le laur\u00e9at du Prix de la libert\u00e9 de la presse recevra 2 500 $ et un certificat de la Commission canadienne pour l&rsquo;UNESCO. Le laur\u00e9at du prix du journalisme local recevra 2 500 $ et le laur\u00e9at du prix du m\u00e9rite professionnel recevra 2 500 $. Le laur\u00e9at du prix de la r\u00e9ussite \u00e9tudiante recevra 1 000 $. Les noms des laur\u00e9ats seront annonc\u00e9s lors du d\u00e9jeuner de remise des 2025 prix de la libert\u00e9 de la presse, qui aura lieu le 1er mai au Centre national des arts \u00e0 Ottawa.<\/p>\n<p>\u00ab Le r\u00f4le du journaliste est d&rsquo;informer le public, de demander des comptes aux puissants et d&rsquo;amplifier les voix qui, autrement, ne seraient pas entendues. Ils mettent en contexte les \u00e9v\u00e9nements qui fa\u00e7onnent notre monde en rapportant ce qui se passe r\u00e9ellement et pourquoi. Nous sommes impatients de rendre hommage \u00e0 ces d\u00e9fenseurs inflexibles de la d\u00e9mocratie lors de notre d\u00e9jeuner annuel de remise des prix \u00bb, a d\u00e9clar\u00e9 Heather Bakken, pr\u00e9sidente de la Libert\u00e9 de la presse Canada.<\/p>\n<p>Les nominations pour tous les prix peuvent \u00eatre faites <a href=\"https:\/\/bit.ly\/WPFCAwardsPrix2025\">ici<\/a>.<\/p>\n<p><strong>La date limite pour les nominations est le 17 f\u00e9vrier 2025, \u00e0 23h59 HNE.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les Prix mondiaux de la libert\u00e9 de la presse Canada r\u00e9compensent ceux qui affrontent le secret, d\u00e9fient l&rsquo;intimidation et surmontent des obstacles dangereux dans leur qu\u00eate de la v\u00e9rit\u00e9. OTTAWA, 2 D\u00c9CEMBRE 2024 \u2013 Libert\u00e9 de la presse Canada a le plaisir d&rsquo;annoncer que les candidatures pour les Prix de la libert\u00e9 de la presse [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":18929,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[10],"tags":[56],"class_list":["post-18927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communique-de-presse","tag-prix-2025"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ouverture des nominations pour les prix 2025 de la libert\u00e9 de la presse - World Press Freedom Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/worldpressfreedomcanada.ca\/fr\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ouverture des nominations pour les prix 2025 de la libert\u00e9 de la presse - World Press Freedom Canada\" \/>\n<meta property=\"og:description\" content=\"Les Prix mondiaux de la libert\u00e9 de la presse Canada r\u00e9compensent ceux qui affrontent le secret, d\u00e9fient l&rsquo;intimidation et surmontent des obstacles dangereux dans leur qu\u00eate de la v\u00e9rit\u00e9. OTTAWA, 2 D\u00c9CEMBRE 2024 \u2013 Libert\u00e9 de la presse Canada a le plaisir d&rsquo;annoncer que les candidatures pour les Prix de la libert\u00e9 de la presse [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/worldpressfreedomcanada.ca\/fr\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\/\" \/>\n<meta property=\"og:site_name\" content=\"World Press Freedom Canada\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-02T12:00:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T00:35:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/worldpressfreedomcanada.ca\/wp-content\/uploads\/2024\/12\/wpfc-nominations-french.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"World Press Freedom Canada\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"World Press Freedom Canada\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/fr\\\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/fr\\\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\\\/\"},\"author\":{\"name\":\"World Press Freedom Canada\",\"@id\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/fr\\\/#\\\/schema\\\/person\\\/1907c0afad865e42882b092f1f38e2bd\"},\"headline\":\"Ouverture des nominations pour les prix 2025 de la libert\u00e9 de la presse\",\"datePublished\":\"2024-12-02T12:00:13+00:00\",\"dateModified\":\"2025-01-23T00:35:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/fr\\\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\\\/\"},\"wordCount\":522,\"image\":{\"@id\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/fr\\\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/wpfc-nominations-french.jpg\",\"keywords\":[\"Prix 2025\"],\"articleSection\":[\"Communiqu\u00e9 de presse\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/fr\\\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\\\/\",\"url\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/fr\\\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\\\/\",\"name\":\"Ouverture des nominations pour les prix 2025 de la libert\u00e9 de la presse - World Press Freedom Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/fr\\\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/fr\\\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/wpfc-nominations-french.jpg\",\"datePublished\":\"2024-12-02T12:00:13+00:00\",\"dateModified\":\"2025-01-23T00:35:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/fr\\\/#\\\/schema\\\/person\\\/1907c0afad865e42882b092f1f38e2bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/fr\\\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/fr\\\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/fr\\\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/wpfc-nominations-french.jpg\",\"contentUrl\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/wpfc-nominations-french.jpg\",\"width\":2000,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/fr\\\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ouverture des nominations pour les prix 2025 de la libert\u00e9 de la presse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/fr\\\/\",\"name\":\"World Press Freedom Canada\",\"description\":\"Championing press freedom, defending democracy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/fr\\\/#\\\/schema\\\/person\\\/1907c0afad865e42882b092f1f38e2bd\",\"name\":\"World Press Freedom Canada\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3acd63b41908ece2f12137641c2f91f2a70ebdd284407ace98159911c9b04604?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3acd63b41908ece2f12137641c2f91f2a70ebdd284407ace98159911c9b04604?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3acd63b41908ece2f12137641c2f91f2a70ebdd284407ace98159911c9b04604?s=96&d=mm&r=g\",\"caption\":\"World Press Freedom Canada\"},\"url\":\"https:\\\/\\\/worldpressfreedomcanada.ca\\\/fr\\\/author\\\/world-press-freedom-canada\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ouverture des nominations pour les prix 2025 de la libert\u00e9 de la presse - World Press Freedom Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/worldpressfreedomcanada.ca\/fr\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\/","og_locale":"fr_FR","og_type":"article","og_title":"Ouverture des nominations pour les prix 2025 de la libert\u00e9 de la presse - World Press Freedom Canada","og_description":"Les Prix mondiaux de la libert\u00e9 de la presse Canada r\u00e9compensent ceux qui affrontent le secret, d\u00e9fient l&rsquo;intimidation et surmontent des obstacles dangereux dans leur qu\u00eate de la v\u00e9rit\u00e9. OTTAWA, 2 D\u00c9CEMBRE 2024 \u2013 Libert\u00e9 de la presse Canada a le plaisir d&rsquo;annoncer que les candidatures pour les Prix de la libert\u00e9 de la presse [&hellip;]","og_url":"https:\/\/worldpressfreedomcanada.ca\/fr\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\/","og_site_name":"World Press Freedom Canada","article_published_time":"2024-12-02T12:00:13+00:00","article_modified_time":"2025-01-23T00:35:10+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/worldpressfreedomcanada.ca\/wp-content\/uploads\/2024\/12\/wpfc-nominations-french.jpg","type":"image\/jpeg"}],"author":"World Press Freedom Canada","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"World Press Freedom Canada","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/worldpressfreedomcanada.ca\/fr\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\/#article","isPartOf":{"@id":"https:\/\/worldpressfreedomcanada.ca\/fr\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\/"},"author":{"name":"World Press Freedom Canada","@id":"https:\/\/worldpressfreedomcanada.ca\/fr\/#\/schema\/person\/1907c0afad865e42882b092f1f38e2bd"},"headline":"Ouverture des nominations pour les prix 2025 de la libert\u00e9 de la presse","datePublished":"2024-12-02T12:00:13+00:00","dateModified":"2025-01-23T00:35:10+00:00","mainEntityOfPage":{"@id":"https:\/\/worldpressfreedomcanada.ca\/fr\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\/"},"wordCount":522,"image":{"@id":"https:\/\/worldpressfreedomcanada.ca\/fr\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\/#primaryimage"},"thumbnailUrl":"https:\/\/worldpressfreedomcanada.ca\/wp-content\/uploads\/2024\/12\/wpfc-nominations-french.jpg","keywords":["Prix 2025"],"articleSection":["Communiqu\u00e9 de presse"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/worldpressfreedomcanada.ca\/fr\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\/","url":"https:\/\/worldpressfreedomcanada.ca\/fr\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\/","name":"Ouverture des nominations pour les prix 2025 de la libert\u00e9 de la presse - World Press Freedom Canada","isPartOf":{"@id":"https:\/\/worldpressfreedomcanada.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/worldpressfreedomcanada.ca\/fr\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\/#primaryimage"},"image":{"@id":"https:\/\/worldpressfreedomcanada.ca\/fr\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\/#primaryimage"},"thumbnailUrl":"https:\/\/worldpressfreedomcanada.ca\/wp-content\/uploads\/2024\/12\/wpfc-nominations-french.jpg","datePublished":"2024-12-02T12:00:13+00:00","dateModified":"2025-01-23T00:35:10+00:00","author":{"@id":"https:\/\/worldpressfreedomcanada.ca\/fr\/#\/schema\/person\/1907c0afad865e42882b092f1f38e2bd"},"breadcrumb":{"@id":"https:\/\/worldpressfreedomcanada.ca\/fr\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/worldpressfreedomcanada.ca\/fr\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/worldpressfreedomcanada.ca\/fr\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\/#primaryimage","url":"https:\/\/worldpressfreedomcanada.ca\/wp-content\/uploads\/2024\/12\/wpfc-nominations-french.jpg","contentUrl":"https:\/\/worldpressfreedomcanada.ca\/wp-content\/uploads\/2024\/12\/wpfc-nominations-french.jpg","width":2000,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/worldpressfreedomcanada.ca\/fr\/ouverture-des-nominations-pour-les-prix-2025-de-la-liberte-de-la-presse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/worldpressfreedomcanada.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Ouverture des nominations pour les prix 2025 de la libert\u00e9 de la presse"}]},{"@type":"WebSite","@id":"https:\/\/worldpressfreedomcanada.ca\/fr\/#website","url":"https:\/\/worldpressfreedomcanada.ca\/fr\/","name":"World Press Freedom Canada","description":"Championing press freedom, defending democracy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/worldpressfreedomcanada.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/worldpressfreedomcanada.ca\/fr\/#\/schema\/person\/1907c0afad865e42882b092f1f38e2bd","name":"World Press Freedom Canada","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3acd63b41908ece2f12137641c2f91f2a70ebdd284407ace98159911c9b04604?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3acd63b41908ece2f12137641c2f91f2a70ebdd284407ace98159911c9b04604?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3acd63b41908ece2f12137641c2f91f2a70ebdd284407ace98159911c9b04604?s=96&d=mm&r=g","caption":"World Press Freedom Canada"},"url":"https:\/\/worldpressfreedomcanada.ca\/fr\/author\/world-press-freedom-canada\/"}]}},"_links":{"self":[{"href":"https:\/\/worldpressfreedomcanada.ca\/fr\/wp-json\/wp\/v2\/posts\/18927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/worldpressfreedomcanada.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/worldpressfreedomcanada.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/worldpressfreedomcanada.ca\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/worldpressfreedomcanada.ca\/fr\/wp-json\/wp\/v2\/comments?post=18927"}],"version-history":[{"count":1,"href":"https:\/\/worldpressfreedomcanada.ca\/fr\/wp-json\/wp\/v2\/posts\/18927\/revisions"}],"predecessor-version":[{"id":19327,"href":"https:\/\/worldpressfreedomcanada.ca\/fr\/wp-json\/wp\/v2\/posts\/18927\/revisions\/19327"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/worldpressfreedomcanada.ca\/fr\/wp-json\/wp\/v2\/media\/18929"}],"wp:attachment":[{"href":"https:\/\/worldpressfreedomcanada.ca\/fr\/wp-json\/wp\/v2\/media?parent=18927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/worldpressfreedomcanada.ca\/fr\/wp-json\/wp\/v2\/categories?post=18927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/worldpressfreedomcanada.ca\/fr\/wp-json\/wp\/v2\/tags?post=18927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}